{"id":2194,"date":"2023-03-03T23:21:59","date_gmt":"2023-03-03T22:21:59","guid":{"rendered":"https:\/\/vernathermbyvernet.com\/?page_id=2194"},"modified":"2024-09-07T15:21:27","modified_gmt":"2024-09-07T13:21:27","slug":"environment-vernatherm-by-vernet","status":"publish","type":"page","link":"https:\/\/vernathermbyvernet.com\/index.php\/environment-vernatherm-by-vernet\/","title":{"rendered":"Environment &#8211; Vernatherm by Vernet"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2194\" class=\"elementor elementor-2194\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d5cd0ef elementor-section-full_width elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"d5cd0ef\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c336c3c\" data-id=\"c336c3c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb62533 elementor-widget elementor-widget-spacer\" data-id=\"cb62533\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<header class=\"elementor-section elementor-top-section elementor-element elementor-element-2a92751e elementor-section-full_width elementor-section-content-middle elementor-reverse-tablet elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"2a92751e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8cbe663\" data-id=\"8cbe663\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06f8872 elementor-widget elementor-widget-image\" data-id=\"06f8872\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/vernathermbyvernet.com\/wp-content\/uploads\/2022\/06\/vernatherm_color.png\" title=\"Vernatherm by Vernet\" alt=\"Vernatherm by Vernet\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8d87c75\" data-id=\"8d87c75\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4c21032\" data-id=\"4c21032\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b21f38e elementor-widget elementor-widget-heading\" data-id=\"b21f38e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-xl\">Precision thermal management systems<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29d0dc2 elementor-section-content-middle elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29d0dc2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d4a30a\" data-id=\"5d4a30a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e73dff2 elementor-nav-menu__align-justify elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"e73dff2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-angle-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;layout&quot;:&quot;horizontal&quot;,&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-drop-out\">\n\t\t\t\t<ul id=\"menu-1-e73dff2\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-1209\"><a href=\"https:\/\/vernathermbyvernet.com\/\" class=\"elementor-item\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2178\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/history-of-vernatherm-vernatherm-by-vernet\/\" class=\"elementor-item\">Who We Are<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1871\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/history-of-vernatherm-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Vernatherm History<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2684\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/about-vernet-group\/\" class=\"elementor-sub-item\">About Vernet Group<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3191\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/brands-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Vernet Group Brands<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1013\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/industries-served-vernatherm-by-vernet\/\" class=\"elementor-item\">Industries Served<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1068\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/commercial-aerospace-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Commercial Aerospace<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1311\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/defense-government-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Defense &#038; Government<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1980\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/energy-power-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Energy &#038; Power<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2161\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/general-aviation-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">General Aviation<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1664\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/products-vernatherm-by-vernet\/\" class=\"elementor-item\">Products<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1605\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/thermal-actuators-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Thermal Actuators<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2026\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/thermostatic-valves-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Thermostatic Valves<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1729\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/pressure-relief-valves-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Pressure Relief Valves<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2135\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/valve-manifolds-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Valve Manifolds<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2312\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/catalog-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Product Catalog<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2483\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/quality-control-vernatherm-by-vernet\/\" class=\"elementor-item\">Quality Control<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1397\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/certifications-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Certifications<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2407\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/product-life-cycle-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Product Life-Cycle<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1951\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/sustainability-vernatherm-by-vernet\/\" class=\"elementor-item\">Sustainability<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3070\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/energy-efficiency-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Energy Efficiency<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3071\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/environment-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Environment<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2275\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/csr-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">CSR Policy<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3072\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/efficiency-assurance-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Efficiency Assurance<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2179\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/contacts-vernatherm-by-vernet\/\" class=\"elementor-item\">Contacts<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2183\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/contact-engineering-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Engineering<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2180\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/contact-sales-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Sales &#038; Business<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2181\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/contact-customer-service-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Customer Service<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2182\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/contact-quality-control-vernatherm-by-vernet\/\" class=\"elementor-sub-item\">Quality Control<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-e73dff2\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-1209\"><a href=\"https:\/\/vernathermbyvernet.com\/\" class=\"elementor-item\" tabindex=\"-1\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2178\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/history-of-vernatherm-vernatherm-by-vernet\/\" class=\"elementor-item\" tabindex=\"-1\">Who We Are<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1871\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/history-of-vernatherm-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Vernatherm History<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2684\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/about-vernet-group\/\" class=\"elementor-sub-item\" tabindex=\"-1\">About Vernet Group<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3191\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/brands-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Vernet Group Brands<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1013\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/industries-served-vernatherm-by-vernet\/\" class=\"elementor-item\" tabindex=\"-1\">Industries Served<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1068\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/commercial-aerospace-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Commercial Aerospace<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1311\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/defense-government-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Defense &#038; Government<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1980\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/energy-power-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Energy &#038; Power<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2161\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/general-aviation-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">General Aviation<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1664\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/products-vernatherm-by-vernet\/\" class=\"elementor-item\" tabindex=\"-1\">Products<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1605\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/thermal-actuators-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Thermal Actuators<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2026\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/thermostatic-valves-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Thermostatic Valves<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1729\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/pressure-relief-valves-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Pressure Relief Valves<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2135\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/valve-manifolds-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Valve Manifolds<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2312\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/catalog-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Product Catalog<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2483\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/quality-control-vernatherm-by-vernet\/\" class=\"elementor-item\" tabindex=\"-1\">Quality Control<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1397\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/certifications-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Certifications<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2407\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/product-life-cycle-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Product Life-Cycle<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1951\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/sustainability-vernatherm-by-vernet\/\" class=\"elementor-item\" tabindex=\"-1\">Sustainability<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3070\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/energy-efficiency-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Energy Efficiency<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3071\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/environment-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Environment<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2275\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/csr-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">CSR Policy<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3072\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/efficiency-assurance-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Efficiency Assurance<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2179\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/contacts-vernatherm-by-vernet\/\" class=\"elementor-item\" tabindex=\"-1\">Contacts<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2183\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/contact-engineering-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Engineering<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2180\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/contact-sales-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Sales &#038; Business<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2181\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/contact-customer-service-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Customer Service<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2182\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/contact-quality-control-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Quality Control<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-908eb9c elementor-section-content-middle elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"908eb9c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c04faf\" data-id=\"3c04faf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8526b69 elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"8526b69\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-angle-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;layout&quot;:&quot;dropdown&quot;,&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-8526b69\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-1209\"><a href=\"https:\/\/vernathermbyvernet.com\/\" class=\"elementor-item\" tabindex=\"-1\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2178\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/history-of-vernatherm-vernatherm-by-vernet\/\" class=\"elementor-item\" tabindex=\"-1\">Who We Are<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1871\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/history-of-vernatherm-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Vernatherm History<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2684\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/about-vernet-group\/\" class=\"elementor-sub-item\" tabindex=\"-1\">About Vernet Group<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3191\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/brands-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Vernet Group Brands<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1013\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/industries-served-vernatherm-by-vernet\/\" class=\"elementor-item\" tabindex=\"-1\">Industries Served<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1068\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/commercial-aerospace-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Commercial Aerospace<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1311\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/defense-government-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Defense &#038; Government<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1980\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/energy-power-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Energy &#038; Power<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2161\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/general-aviation-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">General Aviation<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1664\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/products-vernatherm-by-vernet\/\" class=\"elementor-item\" tabindex=\"-1\">Products<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1605\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/thermal-actuators-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Thermal Actuators<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2026\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/thermostatic-valves-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Thermostatic Valves<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1729\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/pressure-relief-valves-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Pressure Relief Valves<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2135\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/valve-manifolds-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Valve Manifolds<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2312\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/catalog-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Product Catalog<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2483\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/quality-control-vernatherm-by-vernet\/\" class=\"elementor-item\" tabindex=\"-1\">Quality Control<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1397\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/certifications-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Certifications<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2407\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/product-life-cycle-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Product Life-Cycle<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-1951\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/sustainability-vernatherm-by-vernet\/\" class=\"elementor-item\" tabindex=\"-1\">Sustainability<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3070\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/energy-efficiency-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Energy Efficiency<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3071\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/environment-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Environment<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2275\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/csr-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">CSR Policy<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3072\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/efficiency-assurance-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Efficiency Assurance<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-has-children menu-item-2179\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/contacts-vernatherm-by-vernet\/\" class=\"elementor-item\" tabindex=\"-1\">Contacts<\/a><button class=\"sub-menu-toggle\" aria-expanded=\"false\" onClick=\"twentytwentyoneExpandSubMenu(this)\"><span class=\"icon-plus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M18 11.2h-5.2V6h-1.6v5.2H6v1.6h5.2V18h1.6v-5.2H18z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"icon-minus\"><svg class=\"svg-icon\" width=\"18\" height=\"18\" aria-hidden=\"true\" role=\"img\" focusable=\"false\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M6 11h12v2H6z\" fill=\"currentColor\"\/><\/svg><\/span><span class=\"screen-reader-text\">Open menu<\/span><\/button>\n<ul class=\"sub-menu elementor-nav-menu--dropdown\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2183\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/contact-engineering-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Engineering<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2180\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/contact-sales-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Sales &#038; Business<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2181\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/contact-customer-service-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Customer Service<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-2182\"><a href=\"https:\/\/vernathermbyvernet.com\/index.php\/contact-quality-control-vernatherm-by-vernet\/\" class=\"elementor-sub-item\" tabindex=\"-1\">Quality Control<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-71acb3a elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"71acb3a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;triangle-asymmetrical&quot;,&quot;shape_divider_bottom&quot;:&quot;triangle-asymmetrical&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M738,99l262-93V0H0v5.6L738,99z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M737.9,94.7L0,0v100h1000V0L737.9,94.7z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d3a482f\" data-id=\"d3a482f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6037c13 elementor-widget elementor-widget-heading\" data-id=\"6037c13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-large\">Environment<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ee38f0 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7ee38f0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-134dfb9\" data-id=\"134dfb9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdbf2e9 elementor-widget elementor-widget-image\" data-id=\"cdbf2e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"498\" src=\"https:\/\/vernathermbyvernet.com\/wp-content\/uploads\/2023\/03\/environment2.png\" class=\"attachment-large size-large wp-image-2196\" alt=\"Vernatherm by Vernet Environmental Responsibility\" srcset=\"https:\/\/vernathermbyvernet.com\/wp-content\/uploads\/2023\/03\/environment2.png 997w, https:\/\/vernathermbyvernet.com\/wp-content\/uploads\/2023\/03\/environment2-300x199.png 300w, https:\/\/vernathermbyvernet.com\/wp-content\/uploads\/2023\/03\/environment2-768x510.png 768w\" sizes=\"(max-width: 750px) 100vw, 750px\" style=\"width:100%;height:66.4%;max-width:997px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec330b6 elementor-widget elementor-widget-button\" data-id=\"ec330b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/www.vernet-group.com\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-globe-americas\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vernet Global<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1485296 elementor-widget elementor-widget-button\" data-id=\"1485296\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/vernathermbyvernet.com\/index.php\/contact-us-vernatherm-by-vernet\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-hands-helping\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contact Us<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5d12e26\" data-id=\"5d12e26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3ec3e1 elementor-widget elementor-widget-text-editor\" data-id=\"d3ec3e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Environmental Impact Reduction<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0910ed6 elementor-widget elementor-widget-text-editor\" data-id=\"0910ed6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>We recognize that the<b> environmental impact <\/b>of our operations is an integral part of our responsibility as a business. We are committed to designing and producing high-quality thermal controls that meet the needs of our customers, while also minimizing our environmental impact.<\/p><p><br><\/p>\n<p><\/p>\n<p>To achieve this goal, we have implemented several measures to reduce our energy consumption and minimize waste generation throughout our manufacturing processes. We use state-of-the-art equipment that is energy-efficient and we have established internal protocols to optimize the use of resources and minimize waste.<\/p>\n<p><\/p>\n<p>We are also committed to ensuring that the raw materials we use in our products are<b> sourced ethically and responsibly<\/b>. We work closely with our suppliers to verify that their practices align with our environmental and social responsibility standards. We prioritize the use of materials that have a<b> lower environmental impact,<\/b> such as recycled and biodegradable materials, whenever possible.<\/p>\n<p><\/p>\n<p><br><\/p>\n<p><\/p>\n<p>As a modern aerospace component manufacturer,<b> we recognize the importance of reducing our environmental impact<\/b> and are committed to doing our part to ensure a sustainable future.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8676678 elementor-hidden-desktop elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8676678\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e001242\" data-id=\"e001242\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d06b032 elementor-section-content-middle elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d06b032\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;shape_divider_bottom&quot;:&quot;triangle-asymmetrical&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;,&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M737.9,94.7L0,0v100h1000V0L737.9,94.7z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-589526d\" data-id=\"589526d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45093cb elementor-widget elementor-widget-spacer\" data-id=\"45093cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Precision thermal management systems Environment Vernet Global Contact Us Environmental Impact Reduction We recognize that the environmental impact of our operations is an integral part of our responsibility as a business. We are committed to designing and producing high-quality thermal controls that meet the needs of our customers, while also minimizing our environmental impact. To&hellip; <a class=\"more-link\" href=\"https:\/\/vernathermbyvernet.com\/index.php\/environment-vernatherm-by-vernet\/\">Continue reading <span class=\"screen-reader-text\">Environment &#8211; Vernatherm by Vernet<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-2194","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Environment - Vernatherm by Vernet - Vernatherm by Vernet<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vernathermbyvernet.com\/index.php\/environment-vernatherm-by-vernet\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Environment - Vernatherm by Vernet - Vernatherm by Vernet\" \/>\n<meta property=\"og:description\" content=\"Precision thermal management systems Environment Vernet Global Contact Us Environmental Impact Reduction We recognize that the environmental impact of our operations is an integral part of our responsibility as a business. We are committed to designing and producing high-quality thermal controls that meet the needs of our customers, while also minimizing our environmental impact. To&hellip; Continue reading Environment &#8211; Vernatherm by Vernet\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vernathermbyvernet.com\/index.php\/environment-vernatherm-by-vernet\/\" \/>\n<meta property=\"og:site_name\" content=\"Vernatherm by Vernet\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vernatherm\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-07T13:21:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vernathermbyvernet.com\/wp-content\/uploads\/2022\/06\/vernatherm_color.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vernathermbyvernet.com\\\/index.php\\\/environment-vernatherm-by-vernet\\\/\",\"url\":\"https:\\\/\\\/vernathermbyvernet.com\\\/index.php\\\/environment-vernatherm-by-vernet\\\/\",\"name\":\"Environment - Vernatherm by Vernet - Vernatherm by Vernet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vernathermbyvernet.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vernathermbyvernet.com\\\/index.php\\\/environment-vernatherm-by-vernet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vernathermbyvernet.com\\\/index.php\\\/environment-vernatherm-by-vernet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vernathermbyvernet.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/vernatherm_color.png\",\"datePublished\":\"2023-03-03T22:21:59+00:00\",\"dateModified\":\"2024-09-07T13:21:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vernathermbyvernet.com\\\/index.php\\\/environment-vernatherm-by-vernet\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vernathermbyvernet.com\\\/index.php\\\/environment-vernatherm-by-vernet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/vernathermbyvernet.com\\\/index.php\\\/environment-vernatherm-by-vernet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vernathermbyvernet.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/vernatherm_color.png\",\"contentUrl\":\"https:\\\/\\\/vernathermbyvernet.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/vernatherm_color.png\",\"width\":1380,\"height\":295,\"caption\":\"Logo of Vernatherm by Vernet\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vernathermbyvernet.com\\\/index.php\\\/environment-vernatherm-by-vernet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/vernathermbyvernet.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Environment &#8211; Vernatherm by Vernet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vernathermbyvernet.com\\\/#website\",\"url\":\"https:\\\/\\\/vernathermbyvernet.com\\\/\",\"name\":\"Vernatherm by Vernet\",\"description\":\"From innovation to solution\",\"publisher\":{\"@id\":\"https:\\\/\\\/vernathermbyvernet.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vernathermbyvernet.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/vernathermbyvernet.com\\\/#organization\",\"name\":\"Vernatherm by Vernet\",\"url\":\"https:\\\/\\\/vernathermbyvernet.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/vernathermbyvernet.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/vernathermbyvernet.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/vernatherm_color-grey.png\",\"contentUrl\":\"https:\\\/\\\/vernathermbyvernet.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/vernatherm_color-grey.png\",\"width\":1380,\"height\":295,\"caption\":\"Vernatherm by Vernet\"},\"image\":{\"@id\":\"https:\\\/\\\/vernathermbyvernet.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vernatherm\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vernatherm-by-vernet\\\/?viewAsMember=true\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Environment - Vernatherm by Vernet - Vernatherm by Vernet","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vernathermbyvernet.com\/index.php\/environment-vernatherm-by-vernet\/","og_locale":"en_US","og_type":"article","og_title":"Environment - Vernatherm by Vernet - Vernatherm by Vernet","og_description":"Precision thermal management systems Environment Vernet Global Contact Us Environmental Impact Reduction We recognize that the environmental impact of our operations is an integral part of our responsibility as a business. We are committed to designing and producing high-quality thermal controls that meet the needs of our customers, while also minimizing our environmental impact. To&hellip; Continue reading Environment &#8211; Vernatherm by Vernet","og_url":"https:\/\/vernathermbyvernet.com\/index.php\/environment-vernatherm-by-vernet\/","og_site_name":"Vernatherm by Vernet","article_publisher":"https:\/\/www.facebook.com\/Vernatherm","article_modified_time":"2024-09-07T13:21:27+00:00","og_image":[{"url":"https:\/\/vernathermbyvernet.com\/wp-content\/uploads\/2022\/06\/vernatherm_color.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vernathermbyvernet.com\/index.php\/environment-vernatherm-by-vernet\/","url":"https:\/\/vernathermbyvernet.com\/index.php\/environment-vernatherm-by-vernet\/","name":"Environment - Vernatherm by Vernet - Vernatherm by Vernet","isPartOf":{"@id":"https:\/\/vernathermbyvernet.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vernathermbyvernet.com\/index.php\/environment-vernatherm-by-vernet\/#primaryimage"},"image":{"@id":"https:\/\/vernathermbyvernet.com\/index.php\/environment-vernatherm-by-vernet\/#primaryimage"},"thumbnailUrl":"https:\/\/vernathermbyvernet.com\/wp-content\/uploads\/2022\/06\/vernatherm_color.png","datePublished":"2023-03-03T22:21:59+00:00","dateModified":"2024-09-07T13:21:27+00:00","breadcrumb":{"@id":"https:\/\/vernathermbyvernet.com\/index.php\/environment-vernatherm-by-vernet\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vernathermbyvernet.com\/index.php\/environment-vernatherm-by-vernet\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/vernathermbyvernet.com\/index.php\/environment-vernatherm-by-vernet\/#primaryimage","url":"https:\/\/vernathermbyvernet.com\/wp-content\/uploads\/2022\/06\/vernatherm_color.png","contentUrl":"https:\/\/vernathermbyvernet.com\/wp-content\/uploads\/2022\/06\/vernatherm_color.png","width":1380,"height":295,"caption":"Logo of Vernatherm by Vernet"},{"@type":"BreadcrumbList","@id":"https:\/\/vernathermbyvernet.com\/index.php\/environment-vernatherm-by-vernet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/vernathermbyvernet.com\/"},{"@type":"ListItem","position":2,"name":"Environment &#8211; Vernatherm by Vernet"}]},{"@type":"WebSite","@id":"https:\/\/vernathermbyvernet.com\/#website","url":"https:\/\/vernathermbyvernet.com\/","name":"Vernatherm by Vernet","description":"From innovation to solution","publisher":{"@id":"https:\/\/vernathermbyvernet.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vernathermbyvernet.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/vernathermbyvernet.com\/#organization","name":"Vernatherm by Vernet","url":"https:\/\/vernathermbyvernet.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/vernathermbyvernet.com\/#\/schema\/logo\/image\/","url":"https:\/\/vernathermbyvernet.com\/wp-content\/uploads\/2022\/04\/vernatherm_color-grey.png","contentUrl":"https:\/\/vernathermbyvernet.com\/wp-content\/uploads\/2022\/04\/vernatherm_color-grey.png","width":1380,"height":295,"caption":"Vernatherm by Vernet"},"image":{"@id":"https:\/\/vernathermbyvernet.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vernatherm","https:\/\/www.linkedin.com\/company\/vernatherm-by-vernet\/?viewAsMember=true"]}]}},"_links":{"self":[{"href":"https:\/\/vernathermbyvernet.com\/index.php\/wp-json\/wp\/v2\/pages\/2194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vernathermbyvernet.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vernathermbyvernet.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vernathermbyvernet.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/vernathermbyvernet.com\/index.php\/wp-json\/wp\/v2\/comments?post=2194"}],"version-history":[{"count":16,"href":"https:\/\/vernathermbyvernet.com\/index.php\/wp-json\/wp\/v2\/pages\/2194\/revisions"}],"predecessor-version":[{"id":3613,"href":"https:\/\/vernathermbyvernet.com\/index.php\/wp-json\/wp\/v2\/pages\/2194\/revisions\/3613"}],"wp:attachment":[{"href":"https:\/\/vernathermbyvernet.com\/index.php\/wp-json\/wp\/v2\/media?parent=2194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}